{"id":1682,"date":"2024-08-12T00:39:53","date_gmt":"2024-08-12T00:39:53","guid":{"rendered":"https:\/\/www.top-queens.com\/product\/1682.html"},"modified":"2024-08-12T00:40:14","modified_gmt":"2024-08-12T00:40:14","slug":"wedding-dress-advanced-design-sense-fine-shiny-sheet-elegant-annual-party-evening-gown","status":"publish","type":"product","link":"https:\/\/www.top-queens.com\/es\/product\/1682.html","title":{"rendered":"Wedding dress Advanced design sense Fine shiny sheet Elegant annual party evening gown"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/sizenote-1.png\" alt=\"\" width=\"776\" height=\"220\" class=\"alignnone size-full wp-image-184\" srcset=\"https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/sizenote-1.png 776w, https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/sizenote-1-300x85.png 300w, https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/sizenote-1-768x218.png 768w, https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/sizenote-1-600x170.png 600w\" sizes=\"auto, (max-width: 776px) 100vw, 776px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/site1-1.png\" alt=\"\" width=\"776\" height=\"759\" class=\"alignnone size-full wp-image-183\" srcset=\"https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/site1-1.png 776w, https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/site1-1-300x293.png 300w, https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/site1-1-768x751.png 768w, https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/site1-1-600x587.png 600w\" sizes=\"auto, (max-width: 776px) 100vw, 776px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/size2.jpg\" alt=\"\" width=\"776\" height=\"928\" class=\"alignnone size-full wp-image-239\" srcset=\"https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/size2.jpg 776w, https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/size2-251x300.jpg 251w, https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/size2-768x918.jpg 768w, https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/size2-300x359.jpg 300w, https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/size2-600x718.jpg 600w\" sizes=\"auto, (max-width: 776px) 100vw, 776px\" \/><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/email.png\" alt=\"\" width=\"776\" height=\"744\" class=\"alignnone size-full wp-image-187\" srcset=\"https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/email.png 776w, https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/email-300x288.png 300w, https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/email-768x736.png 768w, https:\/\/www.top-queens.com\/wp-content\/uploads\/2024\/07\/email-600x575.png 600w\" sizes=\"auto, (max-width: 776px) 100vw, 776px\" \/><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1687,"template":"","meta":[],"product_cat":[19],"product_tag":[],"class_list":{"0":"post-1682","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-mermaid","7":"pa_size-customized","9":"first","10":"instock","11":"sale","12":"shipping-taxable","13":"purchasable","14":"product-type-variable","15":"has-default-attributes"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.top-queens.com\/es\/wp-json\/wp\/v2\/product\/1682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.top-queens.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.top-queens.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.top-queens.com\/es\/wp-json\/wp\/v2\/media\/1687"}],"wp:attachment":[{"href":"https:\/\/www.top-queens.com\/es\/wp-json\/wp\/v2\/media?parent=1682"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.top-queens.com\/es\/wp-json\/wp\/v2\/product_cat?post=1682"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.top-queens.com\/es\/wp-json\/wp\/v2\/product_tag?post=1682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}